{"id":101063,"date":"2025-02-18T15:14:20","date_gmt":"2025-02-18T14:14:20","guid":{"rendered":"https:\/\/baypol.eu\/promotionskolleg\/?p=101063"},"modified":"2025-02-18T15:14:20","modified_gmt":"2025-02-18T14:14:20","slug":"34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political","status":"publish","type":"post","link":"https:\/\/baypol.eu\/promotionskolleg\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\/","title":{"rendered":"34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie &#8211; \u201ePerspectives on human rights: Historical, conceptual, political\u201c"},"content":{"rendered":"<p>Die 34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie, die in Kooperation mit der Deutschen Gesellschaft zur Erforschung des Politischen Denkens (DGEPD) stattfindet und als Jahrestagung der DGEPD fungiert, befasst sich thematisch mit der Idee der Menschenrechte und tr\u00e4gt den Titel \u201ePerspectives on human rights: Historical, conceptual, political\u201c. Die Tagung findet vom 10. bis zum 12. Februar 2025 in Regensburg statt und wird von Prof. Dr. Daniel Eggers und Prof. Dr. Eva Odzuck organisiert.<\/p>\n<p>Ziel der Tagung ist es, Doktorand:innen und Post-Docs aus der Politischen Philosophie, Theorie und Ideengeschichte mit Wissenschaftler:innen ins Gespr\u00e4ch zu bringen, die sich aus verschiedenen Perspektiven mit der Idee der Menschenrechte befassen, und zu einem interdisziplin\u00e4ren Diskurs beizutragen, der historische Betrachtung, philosophisch-begriffliche Analyse und politisch-praktischen Anwendungsbezug miteinander verbindet. Neben den Gastvortr\u00e4gen habe die Doktorand:innen des Bayerischen Promotionskollegs f\u00fcr Politische Theorie die M\u00f6glichkeit, ihre Promotionsprojekte in Form von Kurzvortr\u00e4gen vorzustellen und im Plenum zu diskutieren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die 34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie, die in Kooperation mit der Deutschen Gesellschaft zur Erforschung des Politischen Denkens (DGEPD) stattfindet und als Jahrestagung der DGEPD fungiert, befasst sich thematisch mit der Idee der Menschenrechte und tr\u00e4gt den Titel \u201ePerspectives on human rights: Historical, conceptual, political\u201c. Die Tagung findet vom 10. bis zum [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-101063","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Die 34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie, die in Kooperation mit der Deutschen Gesellschaft zur Erforschung des Politischen Denkens (DGEPD) stattfindet und als Jahrestagung der DGEPD fungiert, befasst sich thematisch mit der Idee der Menschenrechte und tr\u00e4gt den Titel \u201ePerspectives on human rights: Historical, conceptual, political\u201c. Die Tagung findet vom 10. bis zum\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/baypol.eu\/promotionskolleg\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Bayerisches Promotionskolleg Politische Theorie - Eichst\u00e4tt-Ingolstadt\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie \u2013 \u201ePerspectives on human rights: Historical, conceptual, political\u201c - Bayerisches Promotionskolleg Politische Theorie\" \/>\n\t\t<meta property=\"og:description\" content=\"Die 34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie, die in Kooperation mit der Deutschen Gesellschaft zur Erforschung des Politischen Denkens (DGEPD) stattfindet und als Jahrestagung der DGEPD fungiert, befasst sich thematisch mit der Idee der Menschenrechte und tr\u00e4gt den Titel \u201ePerspectives on human rights: Historical, conceptual, political\u201c. Die Tagung findet vom 10. bis zum\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/baypol.eu\/promotionskolleg\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-02-18T14:14:20+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-02-18T14:14:20+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie \u2013 \u201ePerspectives on human rights: Historical, conceptual, political\u201c - Bayerisches Promotionskolleg Politische Theorie\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Die 34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie, die in Kooperation mit der Deutschen Gesellschaft zur Erforschung des Politischen Denkens (DGEPD) stattfindet und als Jahrestagung der DGEPD fungiert, befasst sich thematisch mit der Idee der Menschenrechte und tr\u00e4gt den Titel \u201ePerspectives on human rights: Historical, conceptual, political\u201c. Die Tagung findet vom 10. bis zum\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\\\/#blogposting\",\"name\":\"34. Tagung des Bayerischen Promotionskollegs f\\u00fcr Politische Theorie \\u2013 \\u201ePerspectives on human rights: Historical, conceptual, political\\u201c - Bayerisches Promotionskolleg Politische Theorie\",\"headline\":\"34. Tagung des Bayerischen Promotionskollegs f\\u00fcr Politische Theorie &#8211; \\u201ePerspectives on human rights: Historical, conceptual, political\\u201c\",\"author\":{\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/08\\\/baypol.png\",\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/#articleImage\",\"width\":500,\"height\":70},\"datePublished\":\"2025-02-18T15:14:20+01:00\",\"dateModified\":\"2025-02-18T15:14:20+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\\\/#webpage\"},\"articleSection\":\"Uncategorized\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Uncategorized\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/category\\\/uncategorized\\\/#listItem\",\"position\":2,\"name\":\"Uncategorized\",\"item\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/category\\\/uncategorized\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\\\/#listItem\",\"name\":\"34. Tagung des Bayerischen Promotionskollegs f\\u00fcr Politische Theorie &#8211; \\u201ePerspectives on human rights: Historical, conceptual, political\\u201c\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\\\/#listItem\",\"position\":3,\"name\":\"34. Tagung des Bayerischen Promotionskollegs f\\u00fcr Politische Theorie &#8211; \\u201ePerspectives on human rights: Historical, conceptual, political\\u201c\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Uncategorized\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/#organization\",\"name\":\"Bayerisches Promotionskolleg Politische Theorie\",\"description\":\"Eichst\\u00e4tt-Ingolstadt\",\"url\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/08\\\/baypol.png\",\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\\\/#organizationLogo\",\"width\":500,\"height\":70},\"image\":{\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/26e3e3892e5664b54b2d97d5fcd8c65e71b7306ebe5664a7540b0648c8a86012?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\\\/#webpage\",\"url\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\\\/\",\"name\":\"34. Tagung des Bayerischen Promotionskollegs f\\u00fcr Politische Theorie \\u2013 \\u201ePerspectives on human rights: Historical, conceptual, political\\u201c - Bayerisches Promotionskolleg Politische Theorie\",\"description\":\"Die 34. Tagung des Bayerischen Promotionskollegs f\\u00fcr Politische Theorie, die in Kooperation mit der Deutschen Gesellschaft zur Erforschung des Politischen Denkens (DGEPD) stattfindet und als Jahrestagung der DGEPD fungiert, befasst sich thematisch mit der Idee der Menschenrechte und tr\\u00e4gt den Titel \\u201ePerspectives on human rights: Historical, conceptual, political\\u201c. Die Tagung findet vom 10. bis zum\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2025-02-18T15:14:20+01:00\",\"dateModified\":\"2025-02-18T15:14:20+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/#website\",\"url\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/\",\"name\":\"Bayerisches Promotionskolleg Politische Theorie\",\"description\":\"Eichst\\u00e4tt-Ingolstadt\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/baypol.eu\\\/promotionskolleg\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie \u2013 \u201ePerspectives on human rights: Historical, conceptual, political\u201c - Bayerisches Promotionskolleg Politische Theorie","description":"Die 34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie, die in Kooperation mit der Deutschen Gesellschaft zur Erforschung des Politischen Denkens (DGEPD) stattfindet und als Jahrestagung der DGEPD fungiert, befasst sich thematisch mit der Idee der Menschenrechte und tr\u00e4gt den Titel \u201ePerspectives on human rights: Historical, conceptual, political\u201c. Die Tagung findet vom 10. bis zum","canonical_url":"https:\/\/baypol.eu\/promotionskolleg\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/baypol.eu\/promotionskolleg\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\/#blogposting","name":"34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie \u2013 \u201ePerspectives on human rights: Historical, conceptual, political\u201c - Bayerisches Promotionskolleg Politische Theorie","headline":"34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie &#8211; \u201ePerspectives on human rights: Historical, conceptual, political\u201c","author":{"@id":"https:\/\/baypol.eu\/promotionskolleg\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/baypol.eu\/promotionskolleg\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/baypol.eu\/promotionskolleg\/wp-content\/uploads\/sites\/4\/2022\/08\/baypol.png","@id":"https:\/\/baypol.eu\/promotionskolleg\/#articleImage","width":500,"height":70},"datePublished":"2025-02-18T15:14:20+01:00","dateModified":"2025-02-18T15:14:20+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/baypol.eu\/promotionskolleg\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\/#webpage"},"isPartOf":{"@id":"https:\/\/baypol.eu\/promotionskolleg\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\/#webpage"},"articleSection":"Uncategorized"},{"@type":"BreadcrumbList","@id":"https:\/\/baypol.eu\/promotionskolleg\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/baypol.eu\/promotionskolleg#listItem","position":1,"name":"Home","item":"https:\/\/baypol.eu\/promotionskolleg","nextItem":{"@type":"ListItem","@id":"https:\/\/baypol.eu\/promotionskolleg\/category\/uncategorized\/#listItem","name":"Uncategorized"}},{"@type":"ListItem","@id":"https:\/\/baypol.eu\/promotionskolleg\/category\/uncategorized\/#listItem","position":2,"name":"Uncategorized","item":"https:\/\/baypol.eu\/promotionskolleg\/category\/uncategorized\/","nextItem":{"@type":"ListItem","@id":"https:\/\/baypol.eu\/promotionskolleg\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\/#listItem","name":"34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie &#8211; \u201ePerspectives on human rights: Historical, conceptual, political\u201c"},"previousItem":{"@type":"ListItem","@id":"https:\/\/baypol.eu\/promotionskolleg#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/baypol.eu\/promotionskolleg\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\/#listItem","position":3,"name":"34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie &#8211; \u201ePerspectives on human rights: Historical, conceptual, political\u201c","previousItem":{"@type":"ListItem","@id":"https:\/\/baypol.eu\/promotionskolleg\/category\/uncategorized\/#listItem","name":"Uncategorized"}}]},{"@type":"Organization","@id":"https:\/\/baypol.eu\/promotionskolleg\/#organization","name":"Bayerisches Promotionskolleg Politische Theorie","description":"Eichst\u00e4tt-Ingolstadt","url":"https:\/\/baypol.eu\/promotionskolleg\/","logo":{"@type":"ImageObject","url":"https:\/\/baypol.eu\/promotionskolleg\/wp-content\/uploads\/sites\/4\/2022\/08\/baypol.png","@id":"https:\/\/baypol.eu\/promotionskolleg\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\/#organizationLogo","width":500,"height":70},"image":{"@id":"https:\/\/baypol.eu\/promotionskolleg\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/baypol.eu\/promotionskolleg\/author\/admin\/#author","url":"https:\/\/baypol.eu\/promotionskolleg\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/baypol.eu\/promotionskolleg\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/26e3e3892e5664b54b2d97d5fcd8c65e71b7306ebe5664a7540b0648c8a86012?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/baypol.eu\/promotionskolleg\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\/#webpage","url":"https:\/\/baypol.eu\/promotionskolleg\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\/","name":"34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie \u2013 \u201ePerspectives on human rights: Historical, conceptual, political\u201c - Bayerisches Promotionskolleg Politische Theorie","description":"Die 34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie, die in Kooperation mit der Deutschen Gesellschaft zur Erforschung des Politischen Denkens (DGEPD) stattfindet und als Jahrestagung der DGEPD fungiert, befasst sich thematisch mit der Idee der Menschenrechte und tr\u00e4gt den Titel \u201ePerspectives on human rights: Historical, conceptual, political\u201c. Die Tagung findet vom 10. bis zum","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/baypol.eu\/promotionskolleg\/#website"},"breadcrumb":{"@id":"https:\/\/baypol.eu\/promotionskolleg\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\/#breadcrumblist"},"author":{"@id":"https:\/\/baypol.eu\/promotionskolleg\/author\/admin\/#author"},"creator":{"@id":"https:\/\/baypol.eu\/promotionskolleg\/author\/admin\/#author"},"datePublished":"2025-02-18T15:14:20+01:00","dateModified":"2025-02-18T15:14:20+01:00"},{"@type":"WebSite","@id":"https:\/\/baypol.eu\/promotionskolleg\/#website","url":"https:\/\/baypol.eu\/promotionskolleg\/","name":"Bayerisches Promotionskolleg Politische Theorie","description":"Eichst\u00e4tt-Ingolstadt","inLanguage":"de-DE","publisher":{"@id":"https:\/\/baypol.eu\/promotionskolleg\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Bayerisches Promotionskolleg Politische Theorie - Eichst\u00e4tt-Ingolstadt","og:type":"article","og:title":"34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie \u2013 \u201ePerspectives on human rights: Historical, conceptual, political\u201c - Bayerisches Promotionskolleg Politische Theorie","og:description":"Die 34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie, die in Kooperation mit der Deutschen Gesellschaft zur Erforschung des Politischen Denkens (DGEPD) stattfindet und als Jahrestagung der DGEPD fungiert, befasst sich thematisch mit der Idee der Menschenrechte und tr\u00e4gt den Titel \u201ePerspectives on human rights: Historical, conceptual, political\u201c. Die Tagung findet vom 10. bis zum","og:url":"https:\/\/baypol.eu\/promotionskolleg\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\/","article:published_time":"2025-02-18T14:14:20+00:00","article:modified_time":"2025-02-18T14:14:20+00:00","twitter:card":"summary_large_image","twitter:title":"34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie \u2013 \u201ePerspectives on human rights: Historical, conceptual, political\u201c - Bayerisches Promotionskolleg Politische Theorie","twitter:description":"Die 34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie, die in Kooperation mit der Deutschen Gesellschaft zur Erforschung des Politischen Denkens (DGEPD) stattfindet und als Jahrestagung der DGEPD fungiert, befasst sich thematisch mit der Idee der Menschenrechte und tr\u00e4gt den Titel \u201ePerspectives on human rights: Historical, conceptual, political\u201c. Die Tagung findet vom 10. bis zum"},"aioseo_meta_data":{"post_id":"101063","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-02-18 14:13:16","updated":"2025-06-04 13:20:44","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/baypol.eu\/promotionskolleg\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/baypol.eu\/promotionskolleg\/category\/uncategorized\/\" title=\"Uncategorized\">Uncategorized<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie \u2013 \u201ePerspectives on human rights: Historical, conceptual, political\u201c\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/baypol.eu\/promotionskolleg"},{"label":"Uncategorized","link":"https:\/\/baypol.eu\/promotionskolleg\/category\/uncategorized\/"},{"label":"34. Tagung des Bayerischen Promotionskollegs f\u00fcr Politische Theorie &#8211; \u201ePerspectives on human rights: Historical, conceptual, political\u201c","link":"https:\/\/baypol.eu\/promotionskolleg\/34-tagung-des-bayerischen-promotionskollegs-fuer-politische-theorie-perspectives-on-human-rights-historical-conceptual-political\/"}],"_links":{"self":[{"href":"https:\/\/baypol.eu\/promotionskolleg\/wp-json\/wp\/v2\/posts\/101063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/baypol.eu\/promotionskolleg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/baypol.eu\/promotionskolleg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/baypol.eu\/promotionskolleg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/baypol.eu\/promotionskolleg\/wp-json\/wp\/v2\/comments?post=101063"}],"version-history":[{"count":1,"href":"https:\/\/baypol.eu\/promotionskolleg\/wp-json\/wp\/v2\/posts\/101063\/revisions"}],"predecessor-version":[{"id":101064,"href":"https:\/\/baypol.eu\/promotionskolleg\/wp-json\/wp\/v2\/posts\/101063\/revisions\/101064"}],"wp:attachment":[{"href":"https:\/\/baypol.eu\/promotionskolleg\/wp-json\/wp\/v2\/media?parent=101063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/baypol.eu\/promotionskolleg\/wp-json\/wp\/v2\/categories?post=101063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/baypol.eu\/promotionskolleg\/wp-json\/wp\/v2\/tags?post=101063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}